{"id":3400,"date":"2026-05-01T08:43:56","date_gmt":"2026-05-01T06:43:56","guid":{"rendered":"https:\/\/avicenna-medical-center.borgmeier.media\/home\/"},"modified":"2026-08-28T15:59:11","modified_gmt":"2026-08-28T13:59:11","slug":"home","status":"publish","type":"page","link":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<h1>Quality of life begins with freedom from pain<\/h1>\n<div>At the Roseneck Medical Center, modern diagnostics and personalized treatment go hand in hand. We put people first and aim to help them enjoy a pain-free daily life.<\/div>\n<p><p>\n        <a href=\"#kontaktformular\">Make an appointment<\/a>\n    <\/p>\n<\/p>\n<p><p>\n        <a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/the-practice\/\">Our practice<\/a>\n    <\/p>\n<\/p>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/03\/Design-Avicenna-Medical-Center-scaled.jpg\" alt=\"\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/AdobeStock_621556410.jpg\" alt=\"\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Header6.jpg\" alt=\"\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Ultraschall6.jpg\" alt=\"\"><\/p>\n<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/07\/Design-Avicenna-Medical-Center.png\" alt=\"\"><\/p>\n<div>Specialized Clinic for Diagnostic Radiology, Neurosurgery, and Orthopedics<\/div>\n<div>Roseneck Medical Center<br \/>\nHohenzollerndamm 104<br \/>\n14199 Berlin<\/div>\n<div>\n<h2>Working together for your health<\/h2>\n<div>\n<p>\nAt our historic location in southwest Berlin, we combine modern diagnostics with specialized medical treatment. At the heart of our approach is the close collaboration between our departments of diagnostic radiology, neurosurgery, and orthopedics. The integration of these disciplines streamlines processes, enables rapid coordination, and allows us to ensure personalized care. Modern imaging techniques provide the foundation for well-founded diagnoses, which in turn form the basis for targeted and sustainable treatment decisions.\n<\/p>\n<\/div>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Icon_Medical_Center_Orthopaedie.png\" alt=\"Icon Wirbels\u00e4ule\"><\/p>\n<h3>Spinal Surgery<\/h3>\n<div>From gentle, minimally invasive treatments to complex procedures on the spine and nervous system. <\/div>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/spinal-surgery\/\"><span uk-icon=\"icon: arrow-right; ratio: 1.4\"><\/span><\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/03\/Design-Avicenna-Medical-Center_Icon_Radiologie.png\" alt=\"\"><\/p>\n<h3>Radiology<\/h3>\n<div>State-of-the-art imaging techniques enable precise and rapid diagnosis: MRI, CT, X-ray, and other diagnostic methods.<\/div>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/diagnostic-radiology\/\"><span uk-icon=\"icon: arrow-right; ratio: 1.4\"><\/span><\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Icon_Medical_Center_Orthopaedie.png\" alt=\"Icon Wirbels\u00e4ule\"><\/p>\n<h3>Orthopedics<\/h3>\n<div>Diagnosis and treatment of musculoskeletal disorders and symptoms, with a focus on restoring and maintaining your mobility and freedom from pain.<\/div>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/orthopedics\/\"><span uk-icon=\"icon: arrow-right; ratio: 1.4\"><\/span><\/a><\/p>\n<\/div>\n<h2>4 steps on your journey to greater mobility and a better quality of life<\/h2>\n<ul>\n<li>\n<h3> 1. Listen and understand<\/h3>\n<\/li>\n<li>\n<h3>2.\tMake an accurate diagnosis<\/h3>\n<\/li>\n<li>\n<h3>3.\tProvide personalized treatment<\/h3>\n<\/li>\n<li>\n<h3>4.\tRelieve and heal<\/h3>\n<\/li>\n<\/ul>\n<h2>Your journey to a better quality of life<\/h2>\n<div>\n<p>Our goal is to relieve pain, maintain mobility, and improve your vitality in the long term. Through thorough diagnostics and close interdisciplinary collaboration, we work with you to develop a treatment plan tailored to your individual situation\u2014for noticeable results and a better quality of life in your daily routine. <\/p>\n<p>At the Roseneck Medical Center, we take the time to address your concerns and guide you with expertise and care on your journey back to greater mobility and well-being.<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/diagnostischeRadiologie2.jpg\" alt=\"\"><\/p>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Praxis1.jpg\" alt=\"\"><\/p>\n<h2>Spinal Surgery<\/h2>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/spinal-surgery\/\"><\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/diagnostischeRadiologie1.jpg\" alt=\"\"><\/p>\n<h2>Diagnostic Radiology<\/h2>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/diagnostic-radiology\/\"><\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/08\/Orthopaedie2-1.jpg\" alt=\"\"><\/p>\n<h2>Orthopedics<\/h2>\n<p><a href=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/orthopedics\/\"><\/a><\/p>\n<\/div>\n<div>\n<h2>Personalized consultation \u2013 precise diagnosis \u2013 individualized treatment.<\/h2>\n<div>\n<p>Whether you\u2019re dealing with recurring back pain, unexplained symptoms, or simply want a professional medical evaluation, at the Roseneck Medical Center we take the time to address your concerns. Thanks to our expertise and experience, you\u2019ll receive an accurate diagnosis and treatment that\u2019s truly tailored to your needs\u2014without having to go through the hassle of visiting multiple specialists.<\/p>\n<p>Let\u2019s work together to find out how we can help you. Schedule an appointment today by phone or through our contact form and meet our team in person\u2014we look forward to seeing you.<\/p>\n<\/div>\n<p><a href=\"#kontaktformular\">Contact us now<\/a><\/p>\n<\/div>\n<div>\n<p>\u201eThe good physician treats the disease; the great physician treats the patient who has the disease.\u201c<\/p>\n<div>(William Osler)<\/div>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"name\":\"Home \u2013 Panels\",\"type\":\"layout\",\"children\":[{\"name\":\"Hero Home\",\"type\":\"section\",\"props\":{\"class\":\"headerSection\",\"height\":\"section\",\"height_viewport_offset\":true,\"image_position\":\"center-center\",\"image_size\":\"cover\",\"media_focal_point\":\"bottom-center\",\"padding_bottom\":\"none\",\"padding_remove_horizontal\":false,\"padding_top\":\"none\",\"style\":\"\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"position_sticky_offset\":\"80\",\"position_sticky_offset_end\":\"80\",\"prevent_collapse\":true,\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"fragment\",\"props\":{\"class\":\"uk-card-body uk-card-large uk-card uk-card-overlay header-box\",\"margin_bottom\":\"remove\",\"margin_top\":\"remove\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Quality of life begins with freedom from pain\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h1\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"At the Roseneck Medical Center, modern diagnostics and personalized treatment go hand in hand. We put people first and aim to help them enjoy a pain-free daily life.\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}},{\"type\":\"button\",\"props\":{\"button_size\":\"large\",\"class\":\"headerButton\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"Make an appointment\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon\":\"user\",\"icon_align\":\"left\",\"link\":\"#kontaktformular\"}}]},{\"type\":\"button\",\"props\":{\"button_size\":\"large\",\"class\":\"headerButton\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Our practice\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"en\/the-practice\/\"}}]}]}]}]},{\"type\":\"slideshow\",\"props\":{\"height_expand\":false,\"height_viewport_offset\":true,\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"default\",\"margin_top\":\"remove\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"nav\":\"dotnav\",\"nav_align\":\"center\",\"nav_breakpoint\":\"s\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"overlay_animation\":\"parallax\",\"overlay_position\":\"center-left\",\"show_content\":true,\"show_link\":true,\"show_meta\":true,\"show_thumbnail\":true,\"show_title\":true,\"slidenav\":\"\",\"slidenav_breakpoint\":\"s\",\"slidenav_margin\":\"medium\",\"slidenav_outside_breakpoint\":\"xl\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"5\",\"slideshow_autoplay_pause\":false,\"slideshow_min_height\":\"200\",\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"thumbnav_width\":\"100\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/03\/Design-Avicenna-Medical-Center-scaled.jpg\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/08\/AdobeStock_621556410.jpg\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/08\/Header6.jpg\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/08\/Ultraschall6.jpg\"}}]}]}],\"props\":{\"column_gap\":\"collapse\",\"height_viewport_offset\":false,\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"parallax\":false,\"row_gap\":\"collapse\"}}]},{\"type\":\"section\",\"props\":{\"height_viewport\":200,\"id\":\"headerStrip\",\"image_position\":\"center-center\",\"overlap\":false,\"padding_bottom\":\"xsmall\",\"padding_top\":\"xsmall\",\"preserve_color\":false,\"style\":\"primary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"props\":{\"divider\":false,\"layout\":\"1-2,1-2\",\"margin_top\":\"default\",\"row_gap\":\"medium\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_large\":\"1-2\",\"width_medium\":\"1-1\",\"width_small\":\"1-1\"}},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"prevent_collapse\":true,\"vertical_align\":\"middle\",\"width_large\":\"1-2\",\"width_medium\":\"1-1\",\"width_small\":\"1-1\"},\"children\":[{\"type\":\"fragment\",\"props\":{\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"divider\":true,\"layout\":\"1-3,1-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"height_expand\":false,\"height_viewport\":false,\"image\":\"wp-content\/uploads\/2026\/07\/Design-Avicenna-Medical-Center.png\",\"image_svg_color\":\"emphasis\",\"image_width\":130,\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"center\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\",\"visibility\":\"m\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"class\":\"under-hero-text\",\"column_breakpoint\":\"m\",\"content\":\"Specialized Clinic for Diagnostic Radiology, Neurosurgery, and Orthopedics\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"class\":\"under-hero-text\",\"column_breakpoint\":\"m\",\"content\":\"Roseneck Medical Center\\nHohenzollerndamm 104\\n14199 Berlin\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]}]}]}]}],\"name\":\"under-hero-home\"},{\"name\":\"Start1\",\"type\":\"section\",\"props\":{\"animation\":\"slide-bottom-medium\",\"height_viewport\":false,\"image_position\":\"center-center\",\"image_size\":\"cover\",\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"\"},\"children\":[{\"type\":\"row\",\"props\":{\"column_gap\":\"medium\",\"margin_bottom\":\"default\",\"margin_top\":\"medium\",\"row_gap\":\"medium\",\"width\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\"},\"children\":[{\"type\":\"panel\",\"props\":{\"block_align\":\"center\",\"content\":\"\n\n<p>\\nAt our historic location in southwest Berlin, we combine modern diagnostics with specialized medical treatment. At the heart of our approach is the close collaboration between our departments of diagnostic radiology, neurosurgery, and orthopedics. The integration of these disciplines streamlines processes, enables rapid coordination, and allows us to ensure personalized care. Modern imaging techniques provide the foundation for well-founded diagnoses, which in turn form the basis for targeted and sustainable treatment decisions. \\n<\/p>\n\n\\n\",\"content_column_breakpoint\":\"m\",\"height_expand\":false,\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_margin\":\"large\",\"link_size\":\"large\",\"link_style\":\"secondary\",\"link_text\":\"Meet the Doctors\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth_breakpoint\":\"m\",\"meta\":\"\",\"meta_align\":\"above-title\",\"meta_color\":\"primary\",\"meta_element\":\"div\",\"meta_style\":\"h6\",\"text_align\":\"left\",\"text_align_fallback\":\"center\",\"title\":\"Working together for your health\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"}}]}]}]},{\"name\":\"Start 1\",\"type\":\"section\",\"props\":{\"animation\":\"slide-top-small\",\"height_viewport\":false,\"image_effect\":\"parallax\",\"image_parallax_easing\":\"1\",\"image_position\":\"bottom-left\",\"padding_bottom\":\"none\",\"padding_top\":\"none\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\"borders rounded iconStartseite\",\"content\":\"From gentle, minimally invasive treatments to complex procedures on the spine and nervous system. \",\"content_column_breakpoint\":\"m\",\"content_margin_auto\":true,\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/Icon_Medical_Center_Orthopaedie.png\",\"image_align\":\"top\",\"image_alt\":\"Icon Wirbels\u00e4ule\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_height\":\"68\",\"image_link\":false,\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"image_width\":\"68\",\"link\":\"en\/spinal-surgery\/\",\"link_aria_label\":\"Icon f\u00fcr Neurochirurgie\",\"link_style\":\"default\",\"link_text\":\"<span uk-icon=\\\"icon: arrow-right; ratio: 1.4\\\"><\/span>\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"default\",\"position\":\"relative\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Spinal Surgery\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\"borders rounded iconStartseite\",\"content\":\"State-of-the-art imaging techniques enable precise and rapid diagnosis: MRI, CT, X-ray, and other diagnostic methods.\",\"content_column_breakpoint\":\"m\",\"content_margin_auto\":true,\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/03\/Design-Avicenna-Medical-Center_Icon_Radiologie.png\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_height\":\"68\",\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"image_width\":\"68\",\"link\":\"en\/diagnostic-radiology\/\",\"link_aria_label\":\"Icon f\u00fcr Radiologie\",\"link_style\":\"default\",\"link_text\":\"<span uk-icon=\\\"icon: arrow-right; ratio: 1.4\\\"><\/span>\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"default\",\"position\":\"relative\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Radiology\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin_auto\":false}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"blend\":false,\"class\":\"borders rounded iconStartseite\",\"content\":\"Diagnosis and treatment of musculoskeletal disorders and symptoms, with a focus on restoring and maintaining your mobility and freedom from pain.\",\"content_column_breakpoint\":\"m\",\"content_margin_auto\":true,\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/Icon_Medical_Center_Orthopaedie.png\",\"image_align\":\"top\",\"image_alt\":\"Icon Wirbels\u00e4ule\",\"image_expand\":false,\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_height\":\"68\",\"image_link\":false,\"image_svg_animate\":false,\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"image_transition_border\":false,\"image_width\":\"68\",\"link\":\"en\/orthopedics\/\",\"link_aria_label\":\"Icon f\u00fcr Orthop\u00e4die\",\"link_download\":false,\"link_margin\":\"small\",\"link_rel_nofollow\":false,\"link_style\":\"default\",\"link_text\":\"<span uk-icon=\\\"icon: arrow-right; ratio: 1.4\\\"><\/span>\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"default\",\"position\":\"relative\",\"position_top\":\"0\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Orthopedics\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin_auto\":false}}]}],\"props\":{\"column_gap\":\"large\",\"layout\":\"1-3,1-3,1-3\",\"margin_bottom\":\"remove\",\"margin_top\":\"remove\",\"padding_remove_horizontal\":false,\"parallax\":false,\"width\":\"large\"}}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"overlap\":false,\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"preserve_color\":false,\"style\":\"\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"class\":\"rounded\",\"image_position\":\"center-center\",\"padding\":\"large\",\"position_sticky_breakpoint\":\"m\",\"prevent_collapse\":false,\"style\":\"card-default\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"4 steps on your journey to greater mobility and a better quality of life\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_bottom\":\"large\",\"margin_top\":\"default\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"left\",\"title_element\":\"h2\",\"title_style\":\"h2\"}},{\"type\":\"grid\",\"props\":{\"content_align\":false,\"content_column_breakpoint\":\"m\",\"content_dropcap\":false,\"filter\":false,\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_align\":true,\"grid_column_gap\":\"collapse\",\"grid_default\":\"1\",\"grid_divider\":false,\"grid_large\":\"4\",\"grid_medium\":\"\",\"grid_parallax_justify\":false,\"grid_row_align\":true,\"grid_xlarge\":\"4\",\"image_align\":\"top\",\"image_expand\":false,\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"\",\"margin_top\":\"large\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_image\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"show_video\":true,\"text_align\":\"center\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"left\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"grid_item\",\"props\":{\"class\":\"step-1 step\",\"content\":\"\",\"image\":\"\",\"meta\":\"\",\"panel_style\":\"card-primary\",\"title\":\" 1. Listen and understand\"}},{\"type\":\"grid_item\",\"props\":{\"class\":\"step-2 step\",\"panel_style\":\"card-primary\",\"title\":\"2.\\tMake an accurate diagnosis\"}},{\"type\":\"grid_item\",\"props\":{\"class\":\"step-3 step\",\"panel_style\":\"card-primary\",\"title\":\"3.\\tProvide personalized treatment\"}},{\"type\":\"grid_item\",\"props\":{\"class\":\"step-4 step\",\"panel_style\":\"card-primary\",\"title\":\"4.\\tRelieve and heal\"}}]}]}],\"props\":{\"class\":\"rounded\",\"margin_top\":\"default\",\"padding_remove_horizontal\":false,\"parallax\":false,\"width\":\"large\"}}]},{\"type\":\"section\",\"props\":{\"image\":\"wp-content\/uploads\/2026\/03\/Design_Avicenna_Medical_Center_Startseite_Banner_Hintergrud-scaled.jpg\",\"image_position\":\"center-center\",\"image_size\":\"cover\",\"style\":\"primary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"3-5\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Your journey to a better quality of life\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h2\",\"title_style\":\"h1\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Our goal is to relieve pain, maintain mobility, and improve your vitality in the long term. Through thorough diagnostics and close interdisciplinary collaboration, we work with you to develop a treatment plan tailored to your individual situation\u2014for noticeable results and a better quality of life in your daily routine. <\/p>\n\n\\n\\n\n\n<p>At the Roseneck Medical Center, we take the time to address your concerns and guide you with expertise and care on your journey back to greater mobility and well-being.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-5\"},\"children\":[{\"type\":\"image\",\"props\":{\"class\":\"rounded\",\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/diagnostischeRadiologie2.jpg\",\"image_svg_color\":\"emphasis\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"text_align\":\"left\"}}]}],\"props\":{\"layout\":\"3-5,2-5\",\"padding_remove_horizontal\":false}}],\"name\":\"banner\"},{\"name\":\"Start Blue Tiles\",\"type\":\"section\",\"props\":{\"animation\":\"slide-top-small\",\"background_color\":\"#F3F4FF\",\"height_viewport\":false,\"image_effect\":\"parallax\",\"image_parallax_easing\":\"1\",\"image_position\":\"bottom-left\",\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"large\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\" rounded\",\"content_column_breakpoint\":\"m\",\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/Praxis1.jpg\",\"image_align\":\"top\",\"image_expand\":false,\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_link\":false,\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"link\":\"en\/spinal-surgery\/\",\"link_style\":\"default\",\"link_text\":\"\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_image_no_padding\":true,\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"small\",\"panel_style\":\"card-primary\",\"position\":\"relative\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Spinal Surgery\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin\":\"xsmall\",\"title_margin_auto\":true,\"title_style\":\"text-large\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\" rounded\",\"content_column_breakpoint\":\"m\",\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/diagnostischeRadiologie1.jpg\",\"image_align\":\"top\",\"image_expand\":false,\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_link\":false,\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"link\":\"en\/diagnostic-radiology\/\",\"link_style\":\"default\",\"link_text\":\"\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_image_no_padding\":true,\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"small\",\"panel_style\":\"card-primary\",\"position\":\"relative\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Diagnostic Radiology\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin\":\"xsmall\",\"title_margin_auto\":true,\"title_style\":\"text-large\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\" rounded\",\"content_column_breakpoint\":\"m\",\"height_expand\":true,\"image\":\"wp-content\/uploads\/2026\/08\/Orthopaedie2-1.jpg\",\"image_align\":\"top\",\"image_expand\":false,\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_link\":false,\"image_svg_color\":\"emphasis\",\"image_svg_inline\":true,\"link\":\"en\/orthopedics\/\",\"link_style\":\"default\",\"link_text\":\"\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_image_no_padding\":true,\"panel_link\":true,\"panel_link_hover\":\"true\",\"panel_padding\":\"small\",\"panel_style\":\"card-primary\",\"position\":\"relative\",\"position_z_index\":\"1\",\"text_align\":\"center\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title\":\"Orthopedics\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin\":\"xsmall\",\"title_margin_auto\":true,\"title_style\":\"text-large\"}}]}],\"props\":{\"column_gap\":\"medium\",\"layout\":\"1-3,1-3,1-3\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"parallax\":false,\"width\":\"large\"}}]},{\"type\":\"section\",\"props\":{\"background_color\":\"#F3F4FF\",\"image_position\":\"center-center\",\"overlap\":false,\"padding_bottom\":\"large\",\"padding_top\":\"none\",\"preserve_color\":false,\"style\":\"\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"background_color\":\"#FFFFFF\",\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"prevent_collapse\":false},\"children\":[{\"type\":\"panel\",\"props\":{\"block_align\":\"center\",\"content\":\"\n\n<p>Whether you\u2019re dealing with recurring back pain, unexplained symptoms, or simply want a professional medical evaluation, at the Roseneck Medical Center we take the time to address your concerns. Thanks to our expertise and experience, you\u2019ll receive an accurate diagnosis and treatment that\u2019s truly tailored to your needs\u2014without having to go through the hassle of visiting multiple specialists.<\/p>\n\n\\n\\n\\n\n\n<p>Let\u2019s work together to find out how we can help you. Schedule an appointment today by phone or through our contact form and meet our team in person\u2014we look forward to seeing you.<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"content_dropcap\":false,\"height_expand\":false,\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link\":\"#kontaktformular\",\"link_style\":\"default\",\"link_text\":\"Contact us now\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth\":\"2xlarge\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"title\":\"Personalized consultation \u2013 precise diagnosis \u2013 individualized treatment.\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_margin_auto\":false,\"title_style\":\"h2\"}}]}],\"props\":{\"class\":\"rounded\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"padding_remove_horizontal\":false,\"parallax\":false,\"width\":\"large\"}},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"prevent_collapse\":false},\"children\":[{\"type\":\"panel\",\"props\":{\"blend\":false,\"block_align\":\"right\",\"block_align_breakpoint\":\"m\",\"block_align_fallback\":\"center\",\"class\":\"rounded overlap\",\"content\":\"(William Osler)\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth\":\"medium\",\"meta\":\"\u201eThe good physician treats the disease; the great physician treats the patient who has the disease.\u201c\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_padding\":\"default\",\"panel_style\":\"card-primary\",\"position\":\"relative\",\"position_left\":\"0\",\"position_top\":\"0\",\"position_z_index\":\"0\",\"title\":\"\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"}}]}],\"props\":{\"class\":\"rounded overlap\",\"margin_bottom\":\"remove\",\"margin_top\":\"remove\",\"padding_remove_horizontal\":false,\"parallax\":false,\"width\":\"xsmall\"}}]}],\"version\":\"5.0.40\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quality of life begins with freedom from pain At the Roseneck Medical Center, modern diagnostics and personalized treatment go hand in hand. We put people first and aim to help them enjoy a pain-free daily life. Make an appointment Our practice Specialized Clinic for Diagnostic Radiology, Neurosurgery, and Orthopedics Roseneck Medical Center Hohenzollerndamm 104 14199 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3400","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Roseneck Medical Center in Berlin-Wilmersdorf<\/title>\n<meta name=\"description\" content=\"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Roseneck Medical Center in Berlin-Wilmersdorf\" \/>\n<meta property=\"og:description\" content=\"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avicenna-medical-center.borgmeier.media\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Avicenna Medical Center\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T13:59:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\",\"url\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\",\"name\":\"The Roseneck Medical Center in Berlin-Wilmersdorf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#website\"},\"datePublished\":\"2026-05-01T06:43:56+00:00\",\"dateModified\":\"2026-08-28T13:59:11+00:00\",\"description\":\"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\",\"name\":\"Avicenna Medical Center\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#organization\",\"name\":\"Avicenna Medical Center\",\"url\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/apple-touch-icon.png\",\"contentUrl\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/apple-touch-icon.png\",\"width\":180,\"height\":180,\"caption\":\"Avicenna Medical Center\"},\"image\":{\"@id\":\"https:\\\/\\\/avicenna-medical-center.borgmeier.media\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Roseneck Medical Center in Berlin-Wilmersdorf","description":"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"The Roseneck Medical Center in Berlin-Wilmersdorf","og_description":"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck","og_url":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","og_site_name":"Avicenna Medical Center","article_modified_time":"2026-08-28T13:59:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","url":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","name":"The Roseneck Medical Center in Berlin-Wilmersdorf","isPartOf":{"@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#website"},"datePublished":"2026-05-01T06:43:56+00:00","dateModified":"2026-08-28T13:59:11+00:00","description":"Accurate diagnoses and effective treatments are the key to a pain-free, symptom-free daily life: Villa Roseneck","breadcrumb":{"@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avicenna-medical-center.borgmeier.media\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#website","url":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","name":"Avicenna Medical Center","description":"","publisher":{"@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#organization","name":"Avicenna Medical Center","url":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#\/schema\/logo\/image\/","url":"https:\/\/avicenna-medical-center.borgmeier.media\/wp-content\/uploads\/2026\/03\/apple-touch-icon.png","contentUrl":"https:\/\/avicenna-medical-center.borgmeier.media\/wp-content\/uploads\/2026\/03\/apple-touch-icon.png","width":180,"height":180,"caption":"Avicenna Medical Center"},"image":{"@id":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/pages\/3400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/comments?post=3400"}],"version-history":[{"count":34,"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/pages\/3400\/revisions"}],"predecessor-version":[{"id":4652,"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/pages\/3400\/revisions\/4652"}],"wp:attachment":[{"href":"https:\/\/avicenna-medical-center.borgmeier.media\/en\/wp-json\/wp\/v2\/media?parent=3400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}